{"id":10118,"date":"2022-12-14T10:15:47","date_gmt":"2022-12-14T03:15:47","guid":{"rendered":"https:\/\/www.thailuxe.com\/wordpress\/?p=10118"},"modified":"2022-12-14T10:15:47","modified_gmt":"2022-12-14T03:15:47","slug":"%e0%b8%97%e0%b8%a3%e0%b8%b4%e0%b8%9b%e0%b8%99%e0%b8%b3%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a5%e0%b8%b9%e0%b8%81%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/www.thailuxe.com\/wordpress\/%e0%b8%97%e0%b8%a3%e0%b8%b4%e0%b8%9b%e0%b8%99%e0%b8%b3%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a5%e0%b8%b9%e0%b8%81%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%b5\/","title":{"rendered":"\u0e17\u0e23\u0e34\u0e1b\u0e19\u0e33\u0e04\u0e13\u0e30\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22"},"content":{"rendered":"<div>\n<!-- Nextend Smart Slider 3 #219 - BEGIN -->\n<div id=\"n2-ss-219-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-219\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition n2-ss-load-fade \" data-minFontSizedesktopPortrait=\"1\" data-minFontSizedesktopLandscape=\"1\" data-minFontSizetabletPortrait=\"1\" data-minFontSizetabletLandscape=\"1\" data-minFontSizemobilePortrait=\"1\" data-minFontSizemobileLandscape=\"1\" style=\"font-size: 16px;\" data-fontsize=\"16\">\r\n        <div class=\"n2-ss-slider-1 n2-ss-swipe-element n2-ow\" style=\"\">\r\n                        <div class=\"n2-ss-slider-2 n2-ow\">\r\n                                <div class=\"n2-ss-slider-3 n2-ow\" style=\"\">\r\n\r\n                    <div class=\"n2-ss-slide-backgrounds\"><\/div><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"1692\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1692\" style=\"\"><div data-hash=\"e95073854a19553ddea2b4ffa22a8a75\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/18.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/18.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1693\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1693\" style=\"\"><div data-hash=\"6b646ea86d758c3df1a6e85ece33d636\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/17.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/17.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1694\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1694\" style=\"\"><div data-hash=\"7b4d925cf420283adb60570e4a98b8d2\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/16.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/16.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1695\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1695\" style=\"\"><div data-hash=\"5069ea80c101feee9fdbcd7fa84005d9\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/15-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/15-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1696\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1696\" style=\"\"><div data-hash=\"eea35f1440ddf660ee7a9a4b3f01b0af\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/14-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/14-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1697\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1697\" style=\"\"><div data-hash=\"2ab22f6c13973489652d5009799ed477\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/13-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/13-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1698\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1698\" style=\"\"><div data-hash=\"99472df9f05ade354ab9a2c081fbd0b8\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/12-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/12-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1699\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1699\" style=\"\"><div data-hash=\"331ebb277ec0a2996bb2033fb99f9909\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/11-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/11-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1700\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1700\" style=\"\"><div data-hash=\"e0735366f3bbc382f2b1e129f9180e0b\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/10-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/10-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1701\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1701\" style=\"\"><div data-hash=\"bc5926042c2a2b0248f94d586a2302d1\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/9-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/9-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1702\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1702\" style=\"\"><div data-hash=\"2c98b66d72acd80c81c03a64953ed646\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/8-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/8-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1703\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1703\" style=\"\"><div data-hash=\"265565ea1008095c51da299c220aaefb\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/7-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/7-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1704\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1704\" style=\"\"><div data-hash=\"6495dc9499274babcc3b4d1a4630eb8e\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/6-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/6-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1705\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1705\" style=\"\"><div data-hash=\"8dae093a4decf2158476806837d6ef72\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/5-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/5-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1706\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1706\" style=\"\"><div data-hash=\"d218652d4652dcfbda42badff1b12aaa\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/4-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/4-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1707\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1707\" style=\"\"><div data-hash=\"6e0dadadeb4d9f9e6ebfadc7340bc4c0\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/3-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/3-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1708\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1708\" style=\"\"><div data-hash=\"7c78c3f840e3af6e00812e475db15f0e\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/2-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/2-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1709\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1709\" style=\"\"><div data-hash=\"7c0e679d0341de9a11b007e952432060\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/1-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/12\/1-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div>                <\/div>\r\n            <\/div>\r\n            <div data-ssleft=\"0+15\" data-sstop=\"height\/2-previousheight\/2\" id=\"n2-ss-219-arrow-previous\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-previous  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Previous slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTEuNDMzIDE1Ljk5MkwyMi42OSA1LjcxMmMuMzkzLS4zOS4zOTMtMS4wMyAwLTEuNDItLjM5My0uMzktMS4wMy0uMzktMS40MjMgMGwtMTEuOTggMTAuOTRjLS4yMS4yMS0uMy40OS0uMjg1Ljc2LS4wMTUuMjguMDc1LjU2LjI4NC43N2wxMS45OCAxMC45NGMuMzkzLjM5IDEuMDMuMzkgMS40MjQgMCAuMzkzLS40LjM5My0xLjAzIDAtMS40MmwtMTEuMjU3LTEwLjI5IiBmaWxsPSIjZmZmZmZmIiBvcGFjaXR5PSIwLjgiIGZpbGwtcnVsZT0iZXZlbm9kZCIvPjwvc3ZnPg==\" alt=\"Arrow\" \/><\/div><div data-ssright=\"0+15\" data-sstop=\"height\/2-nextheight\/2\" id=\"n2-ss-219-arrow-next\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-next  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Next slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTAuNzIyIDQuMjkzYy0uMzk0LS4zOS0xLjAzMi0uMzktMS40MjcgMC0uMzkzLjM5LS4zOTMgMS4wMyAwIDEuNDJsMTEuMjgzIDEwLjI4LTExLjI4MyAxMC4yOWMtLjM5My4zOS0uMzkzIDEuMDIgMCAxLjQyLjM5NS4zOSAxLjAzMy4zOSAxLjQyNyAwbDEyLjAwNy0xMC45NGMuMjEtLjIxLjMtLjQ5LjI4NC0uNzcuMDE0LS4yNy0uMDc2LS41NS0uMjg2LS43NkwxMC43MiA0LjI5M3oiIGZpbGw9IiNmZmZmZmYiIG9wYWNpdHk9IjAuOCIgZmlsbC1ydWxlPSJldmVub2RkIi8+PC9zdmc+\" alt=\"Arrow\" \/><\/div>\n        <\/div>\r\n        <\/div><div class=\"n2-clear\"><\/div><div id=\"n2-ss-219-spinner\" style=\"display: none;\"><div><div class=\"n2-ss-spinner-simple-white-container\"><div class=\"n2-ss-spinner-simple-white\"><\/div><\/div><\/div><\/div><\/div><\/div>\n<!-- Nextend Smart Slider 3 #219 - END -->\n<\/div>\n<p> \u0e17\u0e23\u0e34\u0e1b\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e1e\u0e35\u0e44\u0e1e\u0e23\u0e4c\u0e21_\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c<br \/>\n\u0e19\u0e33\u0e04\u0e13\u0e30\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 7-10 \u0e18.\u0e04. 2565<br \/>\n\u0e23\u0e27\u0e21\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e41\u0e2d\u0e48\u0e27\u0e21\u0e48\u0e27\u0e19\u0e43\u0e08 \u0e44\u0e1b\u0e44\u0e01\u0e25\u0e2a\u0e38\u0e14\u0e41\u0e14\u0e19\u0e2a\u0e22\u0e32\u0e21<br \/>\n\u0e1a\u0e49\u0e32\u0e19\u0e1c\u0e32\u0e2e\u0e35\u0e49 \u0e15.\u0e42\u0e1b\u0e48\u0e07\u0e07\u0e32\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e2a\u0e32\u0e22, \u0e27\u0e31\u0e14\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e14\u0e2d\u0e22\u0e15\u0e38\u0e07-\u0e1e\u0e23\u0e30\u0e15\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e14\u0e2d\u0e22\u0e15\u0e38\u0e07, \u0e14\u0e2d\u0e22\u0e1c\u0e32\u0e2b\u0e21\u0e35, \u0e14\u0e2d\u0e22\u0e0a\u0e49\u0e32\u0e07, YAYO FARM, \u0e2d\u0e32\u0e02\u0e32\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e27\u0e34\u0e27, \u0e44\u0e23\u0e48\u0e1a\u0e38\u0e0d\u0e23\u0e2d\u0e14 (\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1b\u0e32\u0e23\u0e4c\u0e04), \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e1e\u0e31\u0e19\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e14\u0e33-\u0e27\u0e31\u0e14\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 Caf\u00e9 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e38\u0e14\u0e1f\u0e34\u0e19 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e21\u0e32\u0e25\u0e2d\u0e07\u0e40\u0e15\u0e4a\u0e2d\u0e30, \u0e23\u0e49\u0e32\u0e19\u0e40\u0e21\u0e25\u0e47\u0e14\u0e0a\u0e32, \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e14\u0e2d\u0e22\u0e1c\u0e32\u0e2b\u0e21\u0e35, \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f Dheva special coffee lab \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23 lab Test \u0e01\u0e32\u0e41\u0e1f<br \/>\n\u0e08\u0e1a\u0e17\u0e23\u0e34\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e22\u0e22\u0e34\u0e49\u0e21  #\u0e2d\u0e34\u0e48\u0e21\u0e1a\u0e38\u0e0d_\u0e2d\u0e34\u0e48\u0e21\u0e43\u0e08\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e1e\u0e35\u0e44\u0e1e\u0e23\u0e4c\u0e21_\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e08\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e1b\u0e35\u0e2b\u0e19\u0e49\u0e32 2566 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e19\u0e33\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e44\u0e1b\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19 \u0e23\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e19\u0e30\u0e04\u0e30<\/p>\n ","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e23\u0e34\u0e1b\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e1e\u0e35\u0e44\u0e1e\u0e23\u0e4c\u0e21_\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e19\u0e33\u0e04\u0e13\u0e30\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 7-10 \u0e18.\u0e04. 2565 \u0e23\u0e27\u0e21\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e41\u0e2d\u0e48\u0e27\u0e21\u0e48\u0e27\u0e19\u0e43\u0e08 \u0e44\u0e1b\u0e44\u0e01\u0e25\u0e2a\u0e38\u0e14\u0e41\u0e14\u0e19\u0e2a\u0e22\u0e32\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e1c\u0e32\u0e2e\u0e35\u0e49 \u0e15.\u0e42\u0e1b\u0e48\u0e07\u0e07\u0e32\u0e21 \u0e2d.\u0e41\u0e21\u0e48\u0e2a\u0e32\u0e22, \u0e27\u0e31\u0e14\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e14\u0e2d\u0e22\u0e15\u0e38\u0e07-\u0e1e\u0e23\u0e30\u0e15\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e14\u0e2d\u0e22\u0e15\u0e38\u0e07, \u0e14\u0e2d\u0e22\u0e1c\u0e32\u0e2b\u0e21\u0e35, \u0e14\u0e2d\u0e22\u0e0a\u0e49\u0e32\u0e07, YAYO FARM, \u0e2d\u0e32\u0e02\u0e32\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e27\u0e34\u0e27, \u0e44\u0e23\u0e48\u0e1a\u0e38\u0e0d\u0e23\u0e2d\u0e14 (\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1b\u0e32\u0e23\u0e4c\u0e04), \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e1e\u0e31\u0e19\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e14\u0e33-\u0e27\u0e31\u0e14\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 Caf\u00e9 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2a\u0e38\u0e14\u0e1f\u0e34\u0e19 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e21\u0e32\u0e25\u0e2d\u0e07\u0e40\u0e15\u0e4a\u0e2d\u0e30, \u0e23\u0e49\u0e32\u0e19\u0e40\u0e21\u0e25\u0e47\u0e14\u0e0a\u0e32, \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e14\u0e2d\u0e22\u0e1c\u0e32\u0e2b\u0e21\u0e35, \u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f Dheva special coffee lab \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23 lab Test \u0e01\u0e32\u0e41\u0e1f \u0e08\u0e1a\u0e17\u0e23\u0e34\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e22\u0e22\u0e34\u0e49\u0e21 #\u0e2d\u0e34\u0e48\u0e21\u0e1a\u0e38\u0e0d_\u0e2d\u0e34\u0e48\u0e21\u0e43\u0e08\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e1e\u0e35\u0e1e\u0e35\u0e44\u0e1e\u0e23\u0e4c\u0e21_\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e08\u0e2d\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e1b\u0e35\u0e2b\u0e19\u0e49\u0e32 2566 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e19\u0e33\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e44\u0e1b\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19 \u0e23\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e19\u0e30\u0e04\u0e30<\/p>\n","protected":false},"author":14,"featured_media":10082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-10118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/10118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/comments?post=10118"}],"version-history":[{"count":0,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/10118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media\/10082"}],"wp:attachment":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media?parent=10118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/categories?post=10118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/tags?post=10118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}