{"id":10340,"date":"2023-01-27T16:20:27","date_gmt":"2023-01-27T09:20:27","guid":{"rendered":"https:\/\/www.thailuxe.com\/wordpress\/?p=10340"},"modified":"2023-01-27T16:50:02","modified_gmt":"2023-01-27T09:50:02","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%a1%e0%b8%b4%e0%b8%99%e0%b8%a1%e0%b8%b2%e0%b8%95%e0%b8%a3%e0%b8%90%e0%b8%b2%e0%b8%99-gmp","status":"publish","type":"post","link":"https:\/\/www.thailuxe.com\/wordpress\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%95%e0%b8%a3%e0%b8%a7%e0%b8%88%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%a1%e0%b8%b4%e0%b8%99%e0%b8%a1%e0%b8%b2%e0%b8%95%e0%b8%a3%e0%b8%90%e0%b8%b2%e0%b8%99-gmp\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e41\u0e25\u0e30 HACCP"},"content":{"rendered":"<div>\n<!-- Nextend Smart Slider 3 #228 - BEGIN -->\n<div id=\"n2-ss-228-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-228\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition n2-ss-load-fade \" data-minFontSizedesktopPortrait=\"1\" data-minFontSizedesktopLandscape=\"1\" data-minFontSizetabletPortrait=\"1\" data-minFontSizetabletLandscape=\"1\" data-minFontSizemobilePortrait=\"1\" data-minFontSizemobileLandscape=\"1\" style=\"font-size: 16px;\" data-fontsize=\"16\">\r\n        <div class=\"n2-ss-slider-1 n2-ss-swipe-element n2-ow\" style=\"\">\r\n                        <div class=\"n2-ss-slider-2 n2-ow\">\r\n                                <div class=\"n2-ss-slider-3 n2-ow\" style=\"\">\r\n\r\n                    <div class=\"n2-ss-slide-backgrounds\"><\/div><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"1832\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1832\" style=\"\"><div data-hash=\"24e9e1ba219aa0123b621a07942477e3\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/1-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/1-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1833\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1833\" style=\"\"><div data-hash=\"64355346ec2e9ba7249a3fdcd72666a8\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/2-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/2-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1834\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1834\" style=\"\"><div data-hash=\"120cc8c8c8102e3e232397c98eb33e4e\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/3-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/3-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1835\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1835\" style=\"\"><div data-hash=\"dd2f4969547156e58cc9ba3721d02f53\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/4-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/4-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1836\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1836\" style=\"\"><div data-hash=\"c72f2b0014f367927a9a24031d08c4ff\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/5-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/5-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1837\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1837\" style=\"\"><div data-hash=\"5b0294ee88cd955890feebc2bee18e31\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/6-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/6-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1838\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1838\" style=\"\"><div data-hash=\"7dc1734c150598ad4745a87ba40c171d\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/7-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/7-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1839\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1839\" style=\"\"><div data-hash=\"e83feebe19c4dd146588dda9dc5de83e\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/8-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/8-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1840\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1840\" style=\"\"><div data-hash=\"3ac8f487877cd79eb3f54d1bfd8df1ff\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/9-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/9-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1841\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1841\" style=\"\"><div data-hash=\"7602367c526358ff4a0c2c84bc53c96b\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/10-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/10-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1842\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1842\" style=\"\"><div data-hash=\"56eddc7aa6401cea9cc9b93f3bf7e3f1\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/11-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/11-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1843\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1843\" style=\"\"><div data-hash=\"7d3046a566e857387b7707455cc96718\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/12-2.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/12-2.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1844\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1844\" style=\"\"><div data-hash=\"50832c9deeb6105ad551936035c10122\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/13-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/13-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1845\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1845\" style=\"\"><div data-hash=\"0f7eea4843c6122d0b9947c30a4dc4b8\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/14-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/14-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1846\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1846\" style=\"\"><div data-hash=\"30ba27943734d147c72cd6b6cac12297\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/15-1.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2023\/01\/15-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div>                <\/div>\r\n            <\/div>\r\n            <div data-ssleft=\"0+15\" data-sstop=\"height\/2-previousheight\/2\" id=\"n2-ss-228-arrow-previous\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-previous  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Previous slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTEuNDMzIDE1Ljk5MkwyMi42OSA1LjcxMmMuMzkzLS4zOS4zOTMtMS4wMyAwLTEuNDItLjM5My0uMzktMS4wMy0uMzktMS40MjMgMGwtMTEuOTggMTAuOTRjLS4yMS4yMS0uMy40OS0uMjg1Ljc2LS4wMTUuMjguMDc1LjU2LjI4NC43N2wxMS45OCAxMC45NGMuMzkzLjM5IDEuMDMuMzkgMS40MjQgMCAuMzkzLS40LjM5My0xLjAzIDAtMS40MmwtMTEuMjU3LTEwLjI5IiBmaWxsPSIjZmZmZmZmIiBvcGFjaXR5PSIwLjgiIGZpbGwtcnVsZT0iZXZlbm9kZCIvPjwvc3ZnPg==\" alt=\"Arrow\" \/><\/div><div data-ssright=\"0+15\" data-sstop=\"height\/2-nextheight\/2\" id=\"n2-ss-228-arrow-next\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-next  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Next slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTAuNzIyIDQuMjkzYy0uMzk0LS4zOS0xLjAzMi0uMzktMS40MjcgMC0uMzkzLjM5LS4zOTMgMS4wMyAwIDEuNDJsMTEuMjgzIDEwLjI4LTExLjI4MyAxMC4yOWMtLjM5My4zOS0uMzkzIDEuMDIgMCAxLjQyLjM5NS4zOSAxLjAzMy4zOSAxLjQyNyAwbDEyLjAwNy0xMC45NGMuMjEtLjIxLjMtLjQ5LjI4NC0uNzcuMDE0LS4yNy0uMDc2LS41NS0uMjg2LS43NkwxMC43MiA0LjI5M3oiIGZpbGw9IiNmZmZmZmYiIG9wYWNpdHk9IjAuOCIgZmlsbC1ydWxlPSJldmVub2RkIi8+PC9zdmc+\" alt=\"Arrow\" \/><\/div>\n        <\/div>\r\n        <\/div><div class=\"n2-clear\"><\/div><div id=\"n2-ss-228-spinner\" style=\"display: none;\"><div><div class=\"n2-ss-spinner-simple-white-container\"><div class=\"n2-ss-spinner-simple-white\"><\/div><\/div><\/div><\/div><\/div><\/div>\n<!-- Nextend Smart Slider 3 #228 - END -->\n<\/div>\n<div>\n<div dir=\"auto\">\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e41\u0e25\u0e30 HACCP \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e481 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c<\/div>\n<div dir=\"auto\">\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e41\u0e25\u0e30 HACCP \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e37\u0e2d \u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e22\u0e48\u0e2d\u0e21\u0e17\u0e4d\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e13 \u0e08\u0e38\u0e14\u0e27\u0e34\u0e01\u0e24\u0e15\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 GMP \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e2a\u0e4d\u0e32\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e4d\u0e32\u0e23\u0e30\u0e1a\u0e1a HACCP<\/div>\n<div dir=\"auto\">&#8211; \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e08\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e32\u0e17\u0e34 \u0e2a\u0e38\u0e02\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e21\u0e25\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e4d\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e32\u0e23\u0e17\u0e4d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e19\u0e4d\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e01\u0e25\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e37\u0e19<\/div>\n<div dir=\"auto\">&#8211; \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 HACCP \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 (Process Control) \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e4d\u0e32\u0e04\u0e31\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e01\u0e24\u0e15\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04<\/div>\n<div dir=\"auto\">&#8211; \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e19\u0e16\u0e36\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22<\/div>\n<div dir=\"auto\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2566 \u0e13 \u0e1a\u0e08\u0e01.\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e2d.\u0e40\u0e02\u0e32\u0e22\u0e49\u0e2d\u0e22 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35<\/div>\n<\/div>\n ","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e41\u0e25\u0e30 HACCP \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e481 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566 \u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e41\u0e25\u0e30 HACCP \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e37\u0e2d \u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e22\u0e48\u0e2d\u0e21\u0e17\u0e4d\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e13 \u0e08\u0e38\u0e14\u0e27\u0e34\u0e01\u0e24\u0e15\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 GMP \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e2a\u0e4d\u0e32\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e4d\u0e32\u0e23\u0e30\u0e1a\u0e1a HACCP &#8211; \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 GMP \u0e08\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e32\u0e17\u0e34 \u0e2a\u0e38\u0e02\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e21\u0e25\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e4d\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e32\u0e23\u0e17\u0e4d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e19\u0e4d\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e38\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e01\u0e25\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e37\u0e19 &#8211; \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 HACCP \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 (Process Control) \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48\u0e2a\u0e4d\u0e32\u0e04\u0e31\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e01\u0e24\u0e15\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 &#8211; [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":10339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-10340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/10340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/comments?post=10340"}],"version-history":[{"count":0,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/10340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media\/10339"}],"wp:attachment":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media?parent=10340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/categories?post=10340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/tags?post=10340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}