{"id":9340,"date":"2022-01-25T15:13:06","date_gmt":"2022-01-25T08:13:06","guid":{"rendered":"https:\/\/www.thailuxe.com\/wordpress\/?p=9340"},"modified":"2022-01-25T15:13:06","modified_gmt":"2022-01-25T08:13:06","slug":"%e0%b8%89%e0%b8%b5%e0%b8%94%e0%b8%9e%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%86%e0%b9%88%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%af","status":"publish","type":"post","link":"https:\/\/www.thailuxe.com\/wordpress\/%e0%b8%89%e0%b8%b5%e0%b8%94%e0%b8%9e%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%86%e0%b9%88%e0%b8%b2%e0%b9%80%e0%b8%8a%e0%b8%b7%e0%b9%89%e0%b8%ad%e0%b8%af\/","title":{"rendered":"\u0e09\u0e35\u0e14\u0e1e\u0e48\u0e19\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e2f"},"content":{"rendered":"<div>\n<!-- Nextend Smart Slider 3 #173 - BEGIN -->\n<div id=\"n2-ss-173-align\" class=\"n2-ss-align\"><div class=\"n2-padding\"><div id=\"n2-ss-173\" class=\"n2-ss-slider n2-ow n2-has-hover n2notransition n2-ss-load-fade \" data-minFontSizedesktopPortrait=\"1\" data-minFontSizedesktopLandscape=\"1\" data-minFontSizetabletPortrait=\"1\" data-minFontSizetabletLandscape=\"1\" data-minFontSizemobilePortrait=\"1\" data-minFontSizemobileLandscape=\"1\" style=\"font-size: 16px;\" data-fontsize=\"16\">\r\n        <div class=\"n2-ss-slider-1 n2-ss-swipe-element n2-ow\" style=\"\">\r\n                        <div class=\"n2-ss-slider-2 n2-ow\">\r\n                                <div class=\"n2-ss-slider-3 n2-ow\" style=\"\">\r\n\r\n                    <div class=\"n2-ss-slide-backgrounds\"><\/div><div data-first=\"1\" data-slide-duration=\"0\" data-id=\"1421\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1421\" style=\"\"><div data-hash=\"e0ff1673c4abb8c3ee9a2c17bb1ba0bc\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770572-scaled.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770572-scaled.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1422\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1422\" style=\"\"><div data-hash=\"45b2c8db8f5dd13f59a1cd5e314836f3\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770585-scaled.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770585-scaled.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1423\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1423\" style=\"\"><div data-hash=\"9b36a6eab6d44f99ad2496207cd75c5e\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770595-scaled.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770595-scaled.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div><div data-slide-duration=\"0\" data-id=\"1424\" class=\"n2-ss-slide n2-ss-canvas n2-ow  n2-ss-slide-1424\" style=\"\"><div data-hash=\"656501a81cbc7318c790e0fcd204f92f\" data-desktop=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770565-scaled.jpg\" class=\"n2-ss-slide-background n2-ow\" data-opacity=\"1\" data-blur=\"0\" data-mode=\"fill\" data-x=\"50\" data-y=\"50\"><div class=\"n2-ss-slide-background-mask\" style=\"\"><img decoding=\"async\" title=\"\" src=\"\/\/www.thailuxe.com\/wordpress\/wp-content\/uploads\/2022\/01\/P1770565-scaled.jpg\" alt=\"\" \/><\/div><\/div><div class=\"n2-ss-layers-container n2-ow\" data-csstextalign=\"center\" style=\"\"><\/div><\/div>                <\/div>\r\n            <\/div>\r\n            <div data-ssleft=\"0+15\" data-sstop=\"height\/2-previousheight\/2\" id=\"n2-ss-173-arrow-previous\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-previous  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Previous slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTEuNDMzIDE1Ljk5MkwyMi42OSA1LjcxMmMuMzkzLS4zOS4zOTMtMS4wMyAwLTEuNDItLjM5My0uMzktMS4wMy0uMzktMS40MjMgMGwtMTEuOTggMTAuOTRjLS4yMS4yMS0uMy40OS0uMjg1Ljc2LS4wMTUuMjguMDc1LjU2LjI4NC43N2wxMS45OCAxMC45NGMuMzkzLjM5IDEuMDMuMzkgMS40MjQgMCAuMzkzLS40LjM5My0xLjAzIDAtMS40MmwtMTEuMjU3LTEwLjI5IiBmaWxsPSIjZmZmZmZmIiBvcGFjaXR5PSIwLjgiIGZpbGwtcnVsZT0iZXZlbm9kZCIvPjwvc3ZnPg==\" alt=\"Arrow\" \/><\/div><div data-ssright=\"0+15\" data-sstop=\"height\/2-nextheight\/2\" id=\"n2-ss-173-arrow-next\" class=\"n2-ss-widget n2-ss-widget-display-desktop n2-ss-widget-display-tablet n2-ss-widget-display-mobile nextend-arrow n2-ib n2-ow nextend-arrow-next  nextend-arrow-animated-fade\" style=\"position: absolute;\" role=\"button\" aria-label=\"Next slide\" tabindex=\"0\"><img decoding=\"async\" class=\"n2-ow\" data-no-lazy=\"1\" data-hack=\"data-lazy-src\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMzIiIGhlaWdodD0iMzIiIHZpZXdCb3g9IjAgMCAzMiAzMiIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48cGF0aCBkPSJNMTAuNzIyIDQuMjkzYy0uMzk0LS4zOS0xLjAzMi0uMzktMS40MjcgMC0uMzkzLjM5LS4zOTMgMS4wMyAwIDEuNDJsMTEuMjgzIDEwLjI4LTExLjI4MyAxMC4yOWMtLjM5My4zOS0uMzkzIDEuMDIgMCAxLjQyLjM5NS4zOSAxLjAzMy4zOSAxLjQyNyAwbDEyLjAwNy0xMC45NGMuMjEtLjIxLjMtLjQ5LjI4NC0uNzcuMDE0LS4yNy0uMDc2LS41NS0uMjg2LS43NkwxMC43MiA0LjI5M3oiIGZpbGw9IiNmZmZmZmYiIG9wYWNpdHk9IjAuOCIgZmlsbC1ydWxlPSJldmVub2RkIi8+PC9zdmc+\" alt=\"Arrow\" \/><\/div>\n        <\/div>\r\n        <\/div><div class=\"n2-clear\"><\/div><div id=\"n2-ss-173-spinner\" style=\"display: none;\"><div><div class=\"n2-ss-spinner-simple-white-container\"><div class=\"n2-ss-spinner-simple-white\"><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"n2-ss-173-placeholder\" style=\"position: relative;z-index:2;\"><img decoding=\"async\" style=\"width: 100%; max-width:3000px; display: block;\" class=\"n2-ow\" src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZlcnNpb249IjEuMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iNTAwIiA+PC9zdmc+\" alt=\"Slider\" \/><\/div>\n<!-- Nextend Smart Slider 3 #173 - END -->\n<\/div>\n<div>\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u2013 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e43\u0e19\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e27\u0e34\u0e14-19 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e09\u0e35\u0e14\u0e1e\u0e48\u0e19\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e01\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19 \u0e13 \u0e1a\u0e21\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 (\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2564<\/div>\n ","protected":false},"excerpt":{"rendered":"<p>\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u2013 \u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e43\u0e19\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a\u0e42\u0e04\u0e27\u0e34\u0e14-19 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e09\u0e35\u0e14\u0e1e\u0e48\u0e19\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e2f \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e01\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19 \u0e13 \u0e1a\u0e21\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 (\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2564<\/p>\n","protected":false},"author":14,"featured_media":9335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-9340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activity"],"_links":{"self":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/9340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/comments?post=9340"}],"version-history":[{"count":0,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/posts\/9340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media\/9335"}],"wp:attachment":[{"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/media?parent=9340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/categories?post=9340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailuxe.com\/wordpress\/wp-json\/wp\/v2\/tags?post=9340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}